{"id":1218,"date":"2022-10-10T13:43:07","date_gmt":"2022-10-10T13:43:07","guid":{"rendered":"https:\/\/icumbertidemontonepietralunga.edu.it\/?p=1218"},"modified":"2022-10-10T13:43:07","modified_gmt":"2022-10-10T13:43:07","slug":"arte-specchio-dellanima","status":"publish","type":"post","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2022\/10\/10\/arte-specchio-dellanima\/","title":{"rendered":"Arte specchio dell&#8217;anima"},"content":{"rendered":"<p><a href=\"https:\/\/padlet.com\/mariacalderagrasso\/8fphoz0rbonm8d0u\">Arte specchio dell&#8217;anima e del mondo (padlet.com)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arte specchio dell&#8217;anima e del mondo (padlet.com)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"tags":[359],"class_list":["post-1218","post","type-post","status-publish","format-standard","hentry","tag-proposte-didattiche-pnsd","tipologia-articolo-articoli"],"acf":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":2853,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2023\/09\/23\/lofferta-didattica-tra-arte-e-natura-per-la-tua-classe\/","url_meta":{"origin":1218,"position":0},"title":"L&#8217;offerta didattica tra arte e natura per la tua classe!","author":"Angela Lucaccioni","date":"23 Settembre 2023","format":false,"excerpt":"Un progetto artistico-botanico innovativo composto da visite guidate a importanti musei e orti botanici d'Italia per scoprire l\u2019utilizzo, la storia, le propriet\u00e0 e il significato delle specie vegetali rappresentate nelle pi\u00f9 belle opere d\u2019arte, arricchito da un'attivit\u00e0 di laboratorio con prodotti 100% naturali! Vuoi prenotare il percorso ArteOrto for School\u2026","rel":"","context":"In \"News Aggiornamento e formazione\"","block_context":{"text":"News Aggiornamento e formazione","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/aggiornamento-e-formazione\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2054,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2023\/01\/29\/perugino-learning-500-500-anni-di-arte-x-100-classi-incontri-gratuiti-per-100-classi-delle-scuole-dellumbria-in-occasione-delle-celebrazioni-di-perugino-2023\/","url_meta":{"origin":1218,"position":1},"title":"PERUGINO LEARNING 500% &#8211; 500 anni di arte x 100 classi. Incontri gratuiti per 100 classi delle Scuole dell&#8217;Umbria in occasione delle celebrazioni di Perugino 2023","author":"Angela Lucaccioni","date":"29 Gennaio 2023","format":false,"excerpt":"Egregio Dirigente, trasmettiamo la lettera di presentazione e la scheda di adesione del progetto\u00a0PERUGINO LEARNING 500% - 500 anni di arte x 100 classi. Il progetto, curato da Sistema Museo e realizzato con il contributo del \"Comitato promotore per le celebrazioni per il quinto centenario della morte del pittore Pietro\u2026","rel":"","context":"In \"News Aggiornamento e formazione\"","block_context":{"text":"News Aggiornamento e formazione","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/aggiornamento-e-formazione\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1287,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2022\/10\/20\/offerta-educativa-a-s-2022-2023-sistema-museo\/","url_meta":{"origin":1218,"position":2},"title":"Offerta Educativa a. s. 2022\/2023 SISTEMA MUSEO","author":"Angela Lucaccioni","date":"20 Ottobre 2022","format":false,"excerpt":"Alla c.a. dei Dirigenti Scolastici Gent.mi, Vi allego nell'email il catalogo della nostra offerta educativa per l\u2019anno scolastico 2022\/2023. Quest\u2019anno abbiamo scelto un\u2019impostazione di carattere tematico, con alcuni focus speciali su musei o mostre temporanee o eventi significativi. Le sezioni tematiche sono: - L'ARTE DELL'ARTE. Percorsi e laboratori di arte\u2026","rel":"","context":"In \"News Aggiornamento e formazione\"","block_context":{"text":"News Aggiornamento e formazione","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/aggiornamento-e-formazione\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5216,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2026\/03\/28\/asse-umbertide-perenchies-cronaca-di-una-settimana-tra-arte-scoperte-efarina\/","url_meta":{"origin":1218,"position":3},"title":"Asse Umbertide-P\u00e9renchies: cronaca di una settimana tra arte, scoperte e\u2026farina!","author":"AMINA BOGGI","date":"28 Marzo 2026","format":false,"excerpt":"L\u2019Europa non \u00e8 solo un concetto geografico, ma un\u2019emozione che si costruisce stando insieme. Lo hanno dimostrato i sedici protagonisti (otto studenti delle classi seconde di Umbertide e otto coetanei francesi provenienti da P\u00e9renchies) che hanno vissuto una settimana di scambio Erasmus all\u2019insegna della scoperta e dell'amicizia: un\u2019esperienza che ha\u2026","rel":"","context":"In \"Erasmus + NEWS\"","block_context":{"text":"Erasmus + NEWS","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/erasmus\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4534,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2025\/07\/07\/devenir-une-oeuvre-dart-le-gonfalon-vivant\/","url_meta":{"origin":1218,"position":4},"title":"Devenir une \u0153uvre d\u2019art: le Gonfalon vivant","author":"sara.borsi3@gmail.com","date":"7 Luglio 2025","format":false,"excerpt":"Devenir une \u0153uvre d\u2019art: le Gonfalon vivant \u00e8 un\u2019attivit\u00e0 creativa in francese per studenti di 11-14 anni. In due ore, i partecipanti scoprono un\u2019opera rinascimentale italiana ricostruendola in un tableau vivant. L\u2019attivit\u00e0 sviluppa espressione corporea, collaborazione e consapevolezza del patrimonio artistico e religioso, favorendo il dialogo interculturale attraverso arte e\u2026","rel":"","context":"In \"Buone pratiche secondaria I grado\"","block_context":{"text":"Buone pratiche secondaria I grado","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/buone-pratiche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/07\/photo_6008126602896067275_y.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/07\/photo_6008126602896067275_y.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/07\/photo_6008126602896067275_y.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/07\/photo_6008126602896067275_y.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2096,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2023\/02\/11\/proposta-per-classi-scuole-secondarie-di-1-e-2-grado-partecipazione-giuria-junior-rec-film-festival-2023-rimini\/","url_meta":{"origin":1218,"position":5},"title":"Proposta per classi Scuole Secondarie di 1\u00b0 e 2\u00b0 Grado: Partecipazione GIURIA JUNIOR &#8211; REC FILM FESTIVAL 2023 (Rimini)","author":"Angela Lucaccioni","date":"11 Febbraio 2023","format":false,"excerpt":"E\u2019 con piacere che la Direzione Generale del\u00a0REC Film Festival\u00a0(concorso nazionale per cortometraggi realizzati da ragazzi e giovani autori, in programma a\u00a0Rimini\u00a0dal 4 al 6 maggio 2023)\u00a0sottopone alla Vostra analisi la\u00a0proposta di partecipazione\u00a0all'evento\u00a0rivolta a studenti e classi di\u00a0scuole secondarie di primo e secondo grado\u00a0di tutta Italia. Si tratta di una\u00a0rassegna\u2026","rel":"","context":"In \"News Aggiornamento e formazione\"","block_context":{"text":"News Aggiornamento e formazione","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/aggiornamento-e-formazione\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/1218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/comments?post=1218"}],"version-history":[{"count":1,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/1218\/revisions"}],"predecessor-version":[{"id":1219,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/1218\/revisions\/1219"}],"wp:attachment":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/media?parent=1218"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/tags?post=1218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}