{"id":2841,"date":"2023-09-23T17:44:45","date_gmt":"2023-09-23T17:44:45","guid":{"rendered":"https:\/\/icumbertidemontonepietralunga.edu.it\/?p=2841"},"modified":"2024-07-21T14:57:40","modified_gmt":"2024-07-21T13:57:40","slug":"200-anni-del-canto-alla-sua-donna-di-giacomo-leopardi","status":"publish","type":"post","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2023\/09\/23\/200-anni-del-canto-alla-sua-donna-di-giacomo-leopardi\/","title":{"rendered":"200 anni del canto Alla Sua Donna di Giacomo Leopardi"},"content":{"rendered":"<p style=\"font-weight: 400\"><strong>GIACOMO LEOPARDI &#8211;\u00a0<em>ALLA SUA DONNA\u00a0<\/em>1823 &#8211; 2023<\/strong><\/p>\n<p style=\"font-weight: 400\">Gentili colleghi insegnanti,<\/p>\n<p style=\"font-weight: 400\">il 2023 vede il bicentenario della composizione del canto\u00a0<strong><em>Alla sua donna<\/em><\/strong>\u00a0di\u00a0Giacomo Leopardi, testo poco conosciuto, perch\u00e9 raramente inserito nei testi scolastici, eppure tanto decisivo per conoscere l\u2019opera ed il pensiero del poeta.<\/p>\n<p style=\"font-weight: 400\">Nella sala conferenze dell\u2019associazione che rappresento, in gigantografia, sar\u00e0 possibile visionare l\u2019autografo (foto di un particolare in allegato), preziosa fonte di informazioni sulla genesi del testo.<\/p>\n<p style=\"font-weight: 400\">Vi rinnovo pertanto l\u2019invito a venire insieme alle vostre classi a Recanati dove potrete visitare i luoghi leopardiani (Piazzuola del Sabato del Villaggio, Colle dell\u2019Infinito, Torre del Passero solitario, ecc) e dove potrete soffermarvi sull\u2019analisi della riproduzione dell\u2019inno\u00a0<strong><em>Alla sua donna<\/em><\/strong>\u00a0estremamente utile per comprendere anche la modalit\u00e0 con cui Leopardi componeva i suoi canti.<\/p>\n<p style=\"font-weight: 400\">Le visite sono solitamente guidate dal recanatese Mario Elisei, scrittore di testi su Leopardi e conferenziere del Centro Culturale. Ha pubblicato &#8220;Il mio amico Leopardi&#8221;, &#8221; Il no disperato&#8221;, &#8220;Se la felicit\u00e0 non esiste che cos&#8217;\u00e8 dunque la vita?&#8221; e vari quaderni monografici sul poeta, ma anche da guide specializzate e insegnanti.<\/p>\n<p style=\"font-weight: 400\">Per\u00a0ulteriori\u00a0informazioni su costi e servizi contattare la segreteria del\u00a0Centro Culturale Leopardi di Recanati al n. 3203077716 oppure inviare una mail a\u00a0<a href=\"mailto:info@centroleopardi.it\">info@centroleopardi.it<\/a><\/p>\n<p style=\"font-weight: 400\">Da\u00a0\u00a0quest&#8217;anno vi segnalo due ulteriori proposte formative sulla \u201ccorrispondenza della bellezza&#8221;:<\/p>\n<p style=\"font-weight: 400\">&#8211; il\u00a0<strong>Rinascimento pittorico<\/strong>\u00a0attraverso Lorenzo Lotto e le sue opere esposte presso il museo di Recanati (dove si trovano anche autografi leopardiani);<\/p>\n<p style=\"font-weight: 400\">&#8211; il\u00a0<strong>Romanico<\/strong>: nascita ed evoluzione attraverso le tre abazie della Val di Chienti.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">Con la speranza di vedervi presto a Recanati auguro un buon anno scolastico!<\/p>\n<p style=\"font-weight: 400\">Prof.ssa Milena Tacconi<\/p>\n<p style=\"font-weight: 400\">Presidente del Centro culturale G. Leopardi di Recanati<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIACOMO LEOPARDI &#8211;\u00a0ALLA SUA DONNA\u00a01823 &#8211; 2023 Gentili colleghi insegnanti, il 2023 vede il bicentenario della composizione del canto\u00a0Alla sua donna\u00a0di\u00a0Giacomo Leopardi, testo poco conosciuto, perch\u00e9 raramente inserito nei testi scolastici, eppure tanto decisivo per conoscere [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":2842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"tags":[339],"class_list":["post-2841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-aggiornamento-e-formazione","tipologia-articolo-news"],"acf":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2023\/09\/autografo-Alla-sua-donna.jpg?fit=2023%2C723&ssl=1","jetpack-related-posts":[{"id":824,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2022\/09\/22\/incontro-con-giacomo-leopardi-a-recanati\/","url_meta":{"origin":2841,"position":0},"title":"Incontro con Giacomo Leopardi a Recanati","author":"Angela Lucaccioni","date":"22 Settembre 2022","format":false,"excerpt":"Egregi dirigenti scolastici e colleghi insegnanti, bentrovati. La sfida educativa che ci vede protagonisti sempre pi\u00f9 in prima linea \u00e8 cominciata! La pandemia che per due anni ci ha costretti ad un insegnamento a singhiozzo sembra ormai essere al capolinea e le restrizioni sembrano ormai terminate. E\u2019 con piacere quindi\u2026","rel":"","context":"In \"News Aggiornamento e formazione\"","block_context":{"text":"News Aggiornamento e formazione","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/aggiornamento-e-formazione\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3339,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2023\/11\/25\/io-dico-no\/","url_meta":{"origin":2841,"position":1},"title":"Io dico no!","author":"Natascia Abbruzzese","date":"25 Novembre 2023","format":false,"excerpt":"Il 25 novembre ricorre la Giornata internazionale per l\u2019eliminazione della violenza sulle donne\u00a0 e, purtroppo, in questi giorni, tutti noi abbiamo capito quanto cammino ci sia ancora da fare. Per questo la nostra manifestazione ha come titolo \u201cIo dico no!\u201d. Perch\u00e9 siamo noi, in prima persona, che dobbiamo e possiamo\u2026","rel":"","context":"In \"news\"","block_context":{"text":"news","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2023\/11\/iodicono5.jpeg?fit=769%2C597&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2023\/11\/iodicono5.jpeg?fit=769%2C597&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2023\/11\/iodicono5.jpeg?fit=769%2C597&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2023\/11\/iodicono5.jpeg?fit=769%2C597&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4902,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2025\/11\/07\/grazie-daniela\/","url_meta":{"origin":2841,"position":2},"title":"Grazie Daniela&#8230;","author":"Claudia Picottini","date":"7 Novembre 2025","format":false,"excerpt":"\u00a0 Con profonda tristezza ci stringiamo nel saluto alla nostra cara collega Daniela Rossi, docente di Musica, pianista eccezionale e donna di fine sensibilit\u00e0 e profonda umanit\u00e0. Cara Daniela, noi tutti che abbiamo avuto l'onore di percorrere insieme a te una parte del nostro cammino, ti accompagniamo con profonda riconoscenza\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/11\/IMG_20251107_212549.jpg?fit=1112%2C967&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/11\/IMG_20251107_212549.jpg?fit=1112%2C967&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/11\/IMG_20251107_212549.jpg?fit=1112%2C967&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/11\/IMG_20251107_212549.jpg?fit=1112%2C967&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2025\/11\/IMG_20251107_212549.jpg?fit=1112%2C967&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2299,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2023\/03\/20\/contest-attiviamoci-scuola-attiva-junior-posta-in-arrivo-pgic84800x\/","url_meta":{"origin":2841,"position":3},"title":"Contest AttiviAMOci &#8211; Scuola Attiva Junior Posta in arrivo  PGIC84800X","author":"Angela Lucaccioni","date":"20 Marzo 2023","format":false,"excerpt":"Gentilissimi, come sapete \u00e8 stato avviato il contest di Scuola Attiva junior \u201cAttiviAMOci\u201d, rivolto alle scuole secondarie di I grado, sul fondamentale tema del mangiare sano e dei corretti stili di vita. Gi\u00e0 a partire dal\u00a01\u00b0 marzo\u00a0\u00e8 possibile per l\u2019insegnante referente di plesso\u00a0caricare in piattaforma\u00a0il lavoro di classe (canzone o\u2026","rel":"","context":"In \"News Aggiornamento e formazione\"","block_context":{"text":"News Aggiornamento e formazione","link":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/argomento\/aggiornamento-e-formazione\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3728,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2024\/06\/13\/adozione-libro-di-testo-consigliato\/","url_meta":{"origin":2841,"position":4},"title":"ADOZIONE LIBRO DI TESTO &#8220;consigliato&#8221;","author":"admin","date":"13 Giugno 2024","format":false,"excerpt":"lettera_ai_genitori_per_acquisto_del_testo_consigliato \u00a0 \u00a0 \u00a0","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3754,"url":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/2024\/08\/21\/criteri-e-modalita-per-la-fornitura-gratuita-o-semigratuita-dei-libri-di-testo-per-la-s-24-25\/","url_meta":{"origin":2841,"position":5},"title":"Criteri e modalit\u00e0 per la fornitura gratuita o semigratuita dei libri di testo per l&#8217;A.S. 24-25","author":"admin","date":"21 Agosto 2024","format":false,"excerpt":"Libri di testo per l'anno scolastico 2024-2025 DGR n. 807 del 07.08.2024\u00a0-\u00a0Legge n. 448\/1998, art. 27 e Legge n. 234\/2021 \u2013 Decreto Direzione generale per lo studente, l\u2019inclusione e l\u2019orientamento scolastico del Ministero dell\u2019Istruzione del merito n. 309 del 16.02.2024. Criteri e modalit\u00e0 per la fornitura gratuita o semigratuita dei\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/icumbertidemontonepietralunga.edu.it\/wp-content\/uploads\/2024\/08\/LOGO-BUONO-1-1.png?fit=224%2C233&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/2841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/comments?post=2841"}],"version-history":[{"count":1,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/2841\/revisions"}],"predecessor-version":[{"id":2843,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/posts\/2841\/revisions\/2843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/media\/2842"}],"wp:attachment":[{"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/media?parent=2841"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icumbertidemontonepietralunga.edu.it\/index.php\/wp-json\/wp\/v2\/tags?post=2841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}